{"id":74,"date":"2008-08-21T08:35:00","date_gmt":"2008-08-21T06:35:00","guid":{"rendered":"http:\/\/www.selbstverstaendlich.de\/blog\/?p=74"},"modified":"2008-09-24T20:04:11","modified_gmt":"2008-09-24T18:04:11","slug":"video-bernd-pitz-zu-nachhaltiger-online-kommunikation-in-b2b","status":"publish","type":"post","link":"https:\/\/www.selbstverstaendlich.de\/blog\/video-bernd-pitz-zu-nachhaltiger-online-kommunikation-in-b2b\/2008\/08\/","title":{"rendered":"Video: Bernd Pitz zu nachhaltiger Online-Kommunikation in B2B"},"content":{"rendered":"<p><a title=\"Webcast: Bernd Pitz zu nachhaltiger B2B-Kommunikation im Netz\" href=\"http:\/\/www.media-treff.de\/index.php\/2008\/08\/19\/im-gesprach-mit-bernd-pitz-welche-entwicklungen-in-der-digitalen-b2b-kommunikation-sind-nachhaltig\/\" target=\"_blank\" rel=\"nofollow\">Webcast<\/a> von den <a title=\"W\u00fcrzburger Werbefachgespr\u00e4che\" href=\"http:\/\/www.wwf08.de\" target=\"_blank\" rel=\"nofollow\">46. W\u00fcrzburger Werbefachgespr\u00e4chen<\/a>: <a title=\"Wolfram A. Zabel\" href=\"https:\/\/www.xing.com\/profile\/WolframA_Zabel\/\" target=\"_blank\" rel=\"nofollow\">Wolfram A. Zabel<\/a> hat mich um eine Standortbestimmung zur digitalen B2B-Kommunikation gebeten: Welche Entwicklungen in der digitalen Kommunikation sind wirklich nachhaltig? Wie sieht ein nachhaltiges Online-Marketing in der Aufmerksamkeits-\u00d6konomie in der Praxis aus?<\/p>\n<p>Von Google AdWords zu Brand Communities und Leadgenerierung: Alle reden von Web 2.0 &#8211; auch im B2B-Gesch\u00e4ft? Unternehmen haben eine Website und einen Newsletter. Wozu brauchen sie noch Medien?<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"445\" height=\"364\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullscreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/de.sevenload.com\/pl\/uXMU4tg\/445x364\/swf\" \/><embed type=\"application\/x-shockwave-flash\" width=\"445\" height=\"364\" src=\"http:\/\/de.sevenload.com\/pl\/uXMU4tg\/445x364\/swf\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/p>\n<p>Link: <a href=\"http:\/\/de.sevenload.com\/sendungen\/media-TREFF-de\/folgen\/uXMU4tg-Im-Gespraech-mit-Bernd-Pitz-Welche-Entwicklungen-in-der-digitalen-B2B-Kommunikation-sind-nachhaltig\" target=\"_blank\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/static.sevenload.com\/img\/sevenload.png\" alt=\"Im Gespr\u00e4ch mit Bernd Pitz: Welche Entwicklungen in der digitalen B2B-Kommunikation sind nachhaltig? \" width=\"66\" height=\"10\" \/><\/a><\/p>\n<p>Mehr zu den W\u00fcrzburger Werbefachgespr\u00e4chen unter dem Motto &#8222;Nachhaltigkeit, Glaubw\u00fcrdigkeit, Vertrauen! \u2013 Erfolgsgaranten guter B2B-Kommunikation&#8220; gibt&#8217;s hervorragend dokumentiert beim <a title=\"Media-TREFF: Dokumentation der W\u00fcrzburger Werbefachgespr\u00e4che\" href=\"http:\/\/www.media-treff.de\/index.php\/2008\/07\/02\/wurzburger-werbefachgesprache-mit-dem-trendthema-2008-corporate-social-responsibility-%E2%80%93-experten-dazu-im-gesprach\/\" target=\"_blank\" rel=\"nofollow\">Media-TREFF<\/a> des Vogel-Verlages. Unter den rund 250 Teilnehmern waren Werbeleiter und Marketingchefs gro\u00dfer deutscher Unternehmen sowie CSR-Experten.<\/p>\n<p>Die Diagnose aller sechs Keynote-Speaker war eindeutig: Die Wertewelt hat sich ver\u00e4ndert und das hat auch Auswirkungen auf das gesellschaftliche und soziale Engagement von Unternehmen. Besonders auff\u00e4llig: Der starke Trend zur Individualisierung ist out, ein S\u00e4ttigungsgrad ist erreicht. Und genauso wie sich Privat- und Berufsleben st\u00e4rker verzahnen, so \u00fcberlagern sich auch die entsprechenden Werte. In der Kategorie <a title=\"Im Gespr\u00e4ch: alle Referenten der W\u00fcrzburger Werbefachgespr\u00e4che\" href=\"http:\/\/www.media-treff.de\/index.php\/category\/im-gespraech\/wwf\/\" target=\"_blank\" rel=\"nofollow\">\u201eIm Gespr\u00e4ch\u201c auf media-TREFF.de <\/a>gibt es von allen Referenten und Experten der Veranstaltung Kurzinterviews.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/07\/08\/dr-thomas-kaiser-zu-corporate-social-responsibility-csr-bei-siemens-glaubwurdigkeit-durch-professionalitat\/\" target=\"_blank\" rel=\"nofollow\">Dr. Thomas Kaiser von Siemens<br \/>\n<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/08\/19\/im-gesprach-mit-bernd-pitz-welche-entwicklungen-in-der-digitalen-b2b-kommunikation-sind-nachhaltig\/\" target=\"_blank\" rel=\"nofollow\">Medien- und Unternehmensberater Bernd Pitz<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/06\/30\/jorg-ihlau-zu-perspektiven-von-corporate-social-responsibility-csr-von-political-correctness-zu-effizienter-kommunikation\/\" target=\"_blank\" rel=\"nofollow\">J\u00f6rg Ihlau von Service-Plan Opinion<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/07\/11\/pr-blogger-klaus-eck-zu-unternehmen-und-menschen-im-kampf-um-ihren-guten-ruf-im-netz\/\" target=\"_blank\" rel=\"nofollow\">PR Blogger Klaus Eck<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/08\/12\/astrid-frohloff-zu-corporate-social-responsibility-und-bewegtbild-im-internet\/\" target=\"_blank\" rel=\"nofollow\">Fernsehjournalistin Astrid Frohloff<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/07\/22\/frank-merkel-zum-hype-20-ansatzpunkte-fur-die-b2b-kommunikation-und-effektives-brand-employment\/\" target=\"_blank\" rel=\"nofollow\">Frank Merkel \u2013 Vorstand der B2B-Werbeagentur wob AG<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/08\/14\/dima-beitzke-zu-crossmedialen-kampagnen-und-dem-trend-zur-lead-generierung\/\" target=\"_blank\" rel=\"nofollow\">Online Marketing Manager Dima Beitzke von Nayoki<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/07\/23\/klaus-flettner-zu-herausforderungen-in-der-unternehmens-und-markenkommunikation\/\" target=\"_blank\" rel=\"nofollow\">Klaus Flettner von Change Communication<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/07\/04\/prof-dr-klaus-schonbach-zur-rolle-der-traditionellen-medien-im-marketingmix-von-unternehmen-im-jahr-2012\/\" target=\"_blank\" rel=\"nofollow\">Medienwissenschaftler Prof. Dr. Klaus Sch\u00f6nbach<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/06\/27\/dr-kerstin-ullrich-zur-studie-was-menschen-morgen-bewegt-trends-und-wertewandel-in-deutschland\/\" target=\"_blank\" rel=\"nofollow\">Dr. Kerstin Ullrich vom GIM<\/a><\/li>\n<li><a href=\"http:\/\/www.media-treff.de\/index.php\/2008\/07\/17\/seit-gut-100-tage-im-amt-stefan-ruhling-zum-wandel-von-fachverlagen-zu-modernen-full-service-dienstleistern\/\" target=\"_blank\" rel=\"nofollow\">Fachverlagsmanager Stefan R\u00fchling<\/a><\/li>\n<li><a title=\"Michael Schubert, b-consquent, zu CSR und B2B\" href=\"http:\/\/www.b-consequent.de\/2008\/08\/19\/in-eigener-sache-webcast-zum-thema-csr-und-b2b\/\" target=\"_blank\" rel=\"nofollow\">Medienberater Michael Schubert<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Webcast von den 46. W\u00fcrzburger Werbefachgespr\u00e4chen: Wolfram A. Zabel hat mich um eine Standortbestimmung zur digitalen B2B-Kommunikation gebeten: Welche Entwicklungen in der digitalen Kommunikation sind wirklich nachhaltig? Wie sieht ein nachhaltiges Online-Marketing in der Aufmerksamkeits-\u00d6konomie in der Praxis aus? Von Google AdWords zu Brand Communities und Leadgenerierung: Alle reden von Web 2.0 &#8211; auch im [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[100,4],"tags":[10,158,237,157,35],"class_list":["post-74","post","type-post","status-publish","format-standard","hentry","category-in-eigener-sache","category-veranstaltungen","tag-b2b","tag-csr","tag-video","tag-webcast","tag-wwf08"],"_links":{"self":[{"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/posts\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":0,"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/posts\/74\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/media?parent=74"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/categories?post=74"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.selbstverstaendlich.de\/blog\/wp-json\/wp\/v2\/tags?post=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}